{"id":7698,"date":"2013-03-18T18:00:31","date_gmt":"2013-03-18T17:00:31","guid":{"rendered":"http:\/\/www.china-by-bike.de\/blog\/?p=7698"},"modified":"2019-04-09T16:21:56","modified_gmt":"2019-04-09T14:21:56","slug":"the-long-way-down","status":"publish","type":"post","link":"https:\/\/china-by-bike.de\/blog\/2013\/03\/the-long-way-down\/","title":{"rendered":"The Long Way down"},"content":{"rendered":"<p><strong><a href=\"https:\/\/china-by-bike.de\/touren\/nepal.php\" target=\"blank\">An den H\u00e4ngen des Himalaya<\/a>, 14.03. bis 07.04.2013<\/strong><\/p>\n<p><em>68 km vom Last Resort nach Dulikhel &#8211; allerlei Abst\u00fcrze und ein Schlussanstieg bei sommerlichen 30 Grad<\/em><\/p>\n<p>Die V\u00f6gel zwitschern, die Bl\u00e4tter rauschen, nur alle 15 Minuten dringt die Sirene eines auf der anderen Seite des Tales vorbefahrenden Busses zu uns her\u00fcber. Wir sitzen im gr\u00fcnen Garten des Last Resorts und genie\u00dfen die Morgensonne beim Fr\u00fchst\u00fcck.<\/p>\n<p>Und von nun an ging`s bergab&#8230;<\/p>\n<p>Manfred hat es also gewagt. Nachdem er schon letztes Jahr im Rahmen der Hongkong-London-Tour im Last Resort vorbeikam und seitdem mit dem Gedanken schwanger ging, hat er sich heute morgen von der H\u00e4ngebr\u00fccke, die die Stra\u00dfe mit dem Resort verbindet, 160 Meter in die Tiefe gest\u00fcrzt:<\/p>\n<p><iframe loading=\"lazy\" src=\"http:\/\/player.vimeo.com\/video\/62285818\" width=\"500\" height=\"300\" frameborder=\"0\" webkitAllowFullScreen mozallowfullscreen allowFullScreen><\/iframe><\/p>\n<p>Gl\u00fccklicherweise mit einem elastischen Band an den F\u00fc\u00dfen. Neben ihm wagen noch gut 15 andere den Bungee-Sprung in die Schlucht, so dass unsere Abfahrt sich ein wenig verz\u00f6gert. Wenn gesprungen wird, ist die H\u00e4ngebr\u00fccke gesperrt, und diese ist die einzige Verbindung zwischen den D\u00f6rfer (und damit auch dem Resorts) mit der Stra\u00dfe. Diese hei\u00dft jenseits der Grenze immerhin Friendship Highway und ist die Hauptverbindung zwischen Indien und China. Viel scheint da nicht verbunden zu sein, da wir die Stra\u00dfe mit ihren gelegentlichen Erdmor\u00e4nen fast f\u00fcr uns allein haben.<\/p>\n<p>Sobald die Stra\u00dfe aber nicht mit Sand und Steinen \u00fcberzogen ist, rollt es gut, immerhin fahren wir auf dem Schlussst\u00fcck einer der l\u00e4ngsten Abfahrten der Welt (4.600 Meter H\u00f6henunterschied von der Passh\u00f6he in Tibet bis nach Barbise). Die letzten 1.000 H\u00f6henmeter bergab k\u00f6nnen wir folglich genie\u00dfen und sind nach gut drei Stunden Fahrt und 42 Kilometern gegen 14:00 Uhr in der Talsohle. Mit einem exzellenten Dal Bhat und einigen Erfrischungsgetr\u00e4nken aus Atlanta st\u00e4rken wir uns f\u00fcr den Schlussanstieg mit Bergankunft. Unser Alpe d`Huez heisst heute Dulikhel und warten nach 25 Kilometern und 700 H\u00f6henmetern auf uns. F\u00fcr alle, die sich jetzt gefragt haben, was Dal Bhat ist: Das nepalesische Nationalgericht &#8211; ein Messingteller mit Reis (=Bhat), dazu Linseneintopf (Dal) und meist noch ein bis drei Nebengerichte. Oft ein scharfes Blumenkohlgem\u00fcse und ein paar St\u00fccke Fleischcurry. B\u00f6se Zungen behaupten, Dal Bhat w\u00e4re eint\u00f6nig. Wir behaupten: Es ist \u00e4u\u00dferst schmackhaft und zeigt durchaus Variationen in Geschmack und Auswahl der Nebengerichte. Dal Bhat wird uns noch weiterhin auf der Reise begleiten &#8211; wir werden berichten!<\/p>\n<p>Auf jeden Fall sind die Linsen gute Energiespender (oder war es die Cola?) und der Anstieg nach Dulikhel geht leichter von den Beinen als bef\u00fcrchtet. Kurz vor 18:00 Uhr erreichen wir im wundersch\u00f6nen Abendlicht das Dulikhel Mountain Resort und genie\u00dfen auf der Dachterrasse unser erstes Schmutzbier der Tour.<br \/>\n<!-- default-view.php -->\n<div\n\tclass=\"ngg-galleryoverview default-view \n\t\t\"\n\tid=\"ngg-gallery-31abfd1a5262faf99e179bde2ee4dc14-1\">\n\n\t\t<!-- Thumbnails -->\n\t\t\t\t<div id=\"ngg-image-0\" class=\"ngg-gallery-thumbnail-box \n\t\t\t\t\t\t\t\t\t\t\t\" \n\t\t\t>\n\t\t\t\t\t\t<div class=\"ngg-gallery-thumbnail\">\n\t\t\t<a href=\"https:\/\/china-by-bike.de\/blog\/wp-content\/gallery\/2013-03-18_nepal131\/dsc1124.jpg\"\n\t\t\t\ttitle=\"\"\n\t\t\t\tdata-src=\"https:\/\/china-by-bike.de\/blog\/wp-content\/gallery\/2013-03-18_nepal131\/dsc1124.jpg\"\n\t\t\t\tdata-thumbnail=\"https:\/\/china-by-bike.de\/blog\/wp-content\/gallery\/2013-03-18_nepal131\/thumbs\/thumbs_dsc1124.jpg\"\n\t\t\t\tdata-image-id=\"13635\"\n\t\t\t\tdata-title=\"dsc1124\"\n\t\t\t\tdata-description=\"\"\n\t\t\t\tdata-image-slug=\"dsc1124\"\n\t\t\t\tclass=\"shutterset_31abfd1a5262faf99e179bde2ee4dc14\">\n\t\t\t\t<img\n\t\t\t\t\ttitle=\"dsc1124\"\n\t\t\t\t\talt=\"dsc1124\"\n\t\t\t\t\tsrc=\"https:\/\/china-by-bike.de\/blog\/wp-content\/gallery\/2013-03-18_nepal131\/thumbs\/thumbs_dsc1124.jpg\"\n\t\t\t\t\twidth=\"100\"\n\t\t\t\t\theight=\"75\"\n\t\t\t\t\tstyle=\"max-width:100%;\"\n\t\t\t\t\/>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div> \n\t\t\t\n\t\t\t\t<div id=\"ngg-image-1\" class=\"ngg-gallery-thumbnail-box \n\t\t\t\t\t\t\t\t\t\t\t\" \n\t\t\t>\n\t\t\t\t\t\t<div class=\"ngg-gallery-thumbnail\">\n\t\t\t<a href=\"https:\/\/china-by-bike.de\/blog\/wp-content\/gallery\/2013-03-18_nepal131\/dsc1125.jpg\"\n\t\t\t\ttitle=\"\"\n\t\t\t\tdata-src=\"https:\/\/china-by-bike.de\/blog\/wp-content\/gallery\/2013-03-18_nepal131\/dsc1125.jpg\"\n\t\t\t\tdata-thumbnail=\"https:\/\/china-by-bike.de\/blog\/wp-content\/gallery\/2013-03-18_nepal131\/thumbs\/thumbs_dsc1125.jpg\"\n\t\t\t\tdata-image-id=\"13636\"\n\t\t\t\tdata-title=\"dsc1125\"\n\t\t\t\tdata-description=\"\"\n\t\t\t\tdata-image-slug=\"dsc1125\"\n\t\t\t\tclass=\"shutterset_31abfd1a5262faf99e179bde2ee4dc14\">\n\t\t\t\t<img\n\t\t\t\t\ttitle=\"dsc1125\"\n\t\t\t\t\talt=\"dsc1125\"\n\t\t\t\t\tsrc=\"https:\/\/china-by-bike.de\/blog\/wp-content\/gallery\/2013-03-18_nepal131\/thumbs\/thumbs_dsc1125.jpg\"\n\t\t\t\t\twidth=\"100\"\n\t\t\t\t\theight=\"75\"\n\t\t\t\t\tstyle=\"max-width:100%;\"\n\t\t\t\t\/>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div> \n\t\t\t\n\t\t\t\t<div id=\"ngg-image-2\" class=\"ngg-gallery-thumbnail-box \n\t\t\t\t\t\t\t\t\t\t\t\" \n\t\t\t>\n\t\t\t\t\t\t<div class=\"ngg-gallery-thumbnail\">\n\t\t\t<a href=\"https:\/\/china-by-bike.de\/blog\/wp-content\/gallery\/2013-03-18_nepal131\/dsc1134.jpg\"\n\t\t\t\ttitle=\"\"\n\t\t\t\tdata-src=\"https:\/\/china-by-bike.de\/blog\/wp-content\/gallery\/2013-03-18_nepal131\/dsc1134.jpg\"\n\t\t\t\tdata-thumbnail=\"https:\/\/china-by-bike.de\/blog\/wp-content\/gallery\/2013-03-18_nepal131\/thumbs\/thumbs_dsc1134.jpg\"\n\t\t\t\tdata-image-id=\"13637\"\n\t\t\t\tdata-title=\"dsc1134\"\n\t\t\t\tdata-description=\"\"\n\t\t\t\tdata-image-slug=\"dsc1134\"\n\t\t\t\tclass=\"shutterset_31abfd1a5262faf99e179bde2ee4dc14\">\n\t\t\t\t<img\n\t\t\t\t\ttitle=\"dsc1134\"\n\t\t\t\t\talt=\"dsc1134\"\n\t\t\t\t\tsrc=\"https:\/\/china-by-bike.de\/blog\/wp-content\/gallery\/2013-03-18_nepal131\/thumbs\/thumbs_dsc1134.jpg\"\n\t\t\t\t\twidth=\"100\"\n\t\t\t\t\theight=\"75\"\n\t\t\t\t\tstyle=\"max-width:100%;\"\n\t\t\t\t\/>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div> \n\t\t\t\n\t\t\t\t<div id=\"ngg-image-3\" class=\"ngg-gallery-thumbnail-box \n\t\t\t\t\t\t\t\t\t\t\t\" \n\t\t\t>\n\t\t\t\t\t\t<div class=\"ngg-gallery-thumbnail\">\n\t\t\t<a href=\"https:\/\/china-by-bike.de\/blog\/wp-content\/gallery\/2013-03-18_nepal131\/dsc1139.jpg\"\n\t\t\t\ttitle=\"\"\n\t\t\t\tdata-src=\"https:\/\/china-by-bike.de\/blog\/wp-content\/gallery\/2013-03-18_nepal131\/dsc1139.jpg\"\n\t\t\t\tdata-thumbnail=\"https:\/\/china-by-bike.de\/blog\/wp-content\/gallery\/2013-03-18_nepal131\/thumbs\/thumbs_dsc1139.jpg\"\n\t\t\t\tdata-image-id=\"13638\"\n\t\t\t\tdata-title=\"dsc1139\"\n\t\t\t\tdata-description=\"\"\n\t\t\t\tdata-image-slug=\"dsc1139\"\n\t\t\t\tclass=\"shutterset_31abfd1a5262faf99e179bde2ee4dc14\">\n\t\t\t\t<img\n\t\t\t\t\ttitle=\"dsc1139\"\n\t\t\t\t\talt=\"dsc1139\"\n\t\t\t\t\tsrc=\"https:\/\/china-by-bike.de\/blog\/wp-content\/gallery\/2013-03-18_nepal131\/thumbs\/thumbs_dsc1139.jpg\"\n\t\t\t\t\twidth=\"100\"\n\t\t\t\t\theight=\"75\"\n\t\t\t\t\tstyle=\"max-width:100%;\"\n\t\t\t\t\/>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div> \n\t\t\t\n\t\t\t\t<div id=\"ngg-image-4\" class=\"ngg-gallery-thumbnail-box \n\t\t\t\t\t\t\t\t\t\t\t\" \n\t\t\t>\n\t\t\t\t\t\t<div class=\"ngg-gallery-thumbnail\">\n\t\t\t<a href=\"https:\/\/china-by-bike.de\/blog\/wp-content\/gallery\/2013-03-18_nepal131\/dsc1143.jpg\"\n\t\t\t\ttitle=\"\"\n\t\t\t\tdata-src=\"https:\/\/china-by-bike.de\/blog\/wp-content\/gallery\/2013-03-18_nepal131\/dsc1143.jpg\"\n\t\t\t\tdata-thumbnail=\"https:\/\/china-by-bike.de\/blog\/wp-content\/gallery\/2013-03-18_nepal131\/thumbs\/thumbs_dsc1143.jpg\"\n\t\t\t\tdata-image-id=\"13639\"\n\t\t\t\tdata-title=\"dsc1143\"\n\t\t\t\tdata-description=\"\"\n\t\t\t\tdata-image-slug=\"dsc1143\"\n\t\t\t\tclass=\"shutterset_31abfd1a5262faf99e179bde2ee4dc14\">\n\t\t\t\t<img\n\t\t\t\t\ttitle=\"dsc1143\"\n\t\t\t\t\talt=\"dsc1143\"\n\t\t\t\t\tsrc=\"https:\/\/china-by-bike.de\/blog\/wp-content\/gallery\/2013-03-18_nepal131\/thumbs\/thumbs_dsc1143.jpg\"\n\t\t\t\t\twidth=\"100\"\n\t\t\t\t\theight=\"75\"\n\t\t\t\t\tstyle=\"max-width:100%;\"\n\t\t\t\t\/>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div> \n\t\t\t\n\t\t\t\t<div id=\"ngg-image-5\" class=\"ngg-gallery-thumbnail-box \n\t\t\t\t\t\t\t\t\t\t\t\" \n\t\t\t>\n\t\t\t\t\t\t<div class=\"ngg-gallery-thumbnail\">\n\t\t\t<a href=\"https:\/\/china-by-bike.de\/blog\/wp-content\/gallery\/2013-03-18_nepal131\/dsc1144.jpg\"\n\t\t\t\ttitle=\"\"\n\t\t\t\tdata-src=\"https:\/\/china-by-bike.de\/blog\/wp-content\/gallery\/2013-03-18_nepal131\/dsc1144.jpg\"\n\t\t\t\tdata-thumbnail=\"https:\/\/china-by-bike.de\/blog\/wp-content\/gallery\/2013-03-18_nepal131\/thumbs\/thumbs_dsc1144.jpg\"\n\t\t\t\tdata-image-id=\"13640\"\n\t\t\t\tdata-title=\"dsc1144\"\n\t\t\t\tdata-description=\"\"\n\t\t\t\tdata-image-slug=\"dsc1144\"\n\t\t\t\tclass=\"shutterset_31abfd1a5262faf99e179bde2ee4dc14\">\n\t\t\t\t<img\n\t\t\t\t\ttitle=\"dsc1144\"\n\t\t\t\t\talt=\"dsc1144\"\n\t\t\t\t\tsrc=\"https:\/\/china-by-bike.de\/blog\/wp-content\/gallery\/2013-03-18_nepal131\/thumbs\/thumbs_dsc1144.jpg\"\n\t\t\t\t\twidth=\"100\"\n\t\t\t\t\theight=\"75\"\n\t\t\t\t\tstyle=\"max-width:100%;\"\n\t\t\t\t\/>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div> \n\t\t\t\n\t\t\t\t<div id=\"ngg-image-6\" class=\"ngg-gallery-thumbnail-box \n\t\t\t\t\t\t\t\t\t\t\t\" \n\t\t\t>\n\t\t\t\t\t\t<div class=\"ngg-gallery-thumbnail\">\n\t\t\t<a href=\"https:\/\/china-by-bike.de\/blog\/wp-content\/gallery\/2013-03-18_nepal131\/dsc1151.jpg\"\n\t\t\t\ttitle=\"\"\n\t\t\t\tdata-src=\"https:\/\/china-by-bike.de\/blog\/wp-content\/gallery\/2013-03-18_nepal131\/dsc1151.jpg\"\n\t\t\t\tdata-thumbnail=\"https:\/\/china-by-bike.de\/blog\/wp-content\/gallery\/2013-03-18_nepal131\/thumbs\/thumbs_dsc1151.jpg\"\n\t\t\t\tdata-image-id=\"13641\"\n\t\t\t\tdata-title=\"dsc1151\"\n\t\t\t\tdata-description=\"\"\n\t\t\t\tdata-image-slug=\"dsc1151\"\n\t\t\t\tclass=\"shutterset_31abfd1a5262faf99e179bde2ee4dc14\">\n\t\t\t\t<img\n\t\t\t\t\ttitle=\"dsc1151\"\n\t\t\t\t\talt=\"dsc1151\"\n\t\t\t\t\tsrc=\"https:\/\/china-by-bike.de\/blog\/wp-content\/gallery\/2013-03-18_nepal131\/thumbs\/thumbs_dsc1151.jpg\"\n\t\t\t\t\twidth=\"100\"\n\t\t\t\t\theight=\"75\"\n\t\t\t\t\tstyle=\"max-width:100%;\"\n\t\t\t\t\/>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div> \n\t\t\t\n\t\t\t\t<div id=\"ngg-image-7\" class=\"ngg-gallery-thumbnail-box \n\t\t\t\t\t\t\t\t\t\t\t\" \n\t\t\t>\n\t\t\t\t\t\t<div class=\"ngg-gallery-thumbnail\">\n\t\t\t<a href=\"https:\/\/china-by-bike.de\/blog\/wp-content\/gallery\/2013-03-18_nepal131\/dsc1153.jpg\"\n\t\t\t\ttitle=\"\"\n\t\t\t\tdata-src=\"https:\/\/china-by-bike.de\/blog\/wp-content\/gallery\/2013-03-18_nepal131\/dsc1153.jpg\"\n\t\t\t\tdata-thumbnail=\"https:\/\/china-by-bike.de\/blog\/wp-content\/gallery\/2013-03-18_nepal131\/thumbs\/thumbs_dsc1153.jpg\"\n\t\t\t\tdata-image-id=\"13642\"\n\t\t\t\tdata-title=\"dsc1153\"\n\t\t\t\tdata-description=\"\"\n\t\t\t\tdata-image-slug=\"dsc1153\"\n\t\t\t\tclass=\"shutterset_31abfd1a5262faf99e179bde2ee4dc14\">\n\t\t\t\t<img\n\t\t\t\t\ttitle=\"dsc1153\"\n\t\t\t\t\talt=\"dsc1153\"\n\t\t\t\t\tsrc=\"https:\/\/china-by-bike.de\/blog\/wp-content\/gallery\/2013-03-18_nepal131\/thumbs\/thumbs_dsc1153.jpg\"\n\t\t\t\t\twidth=\"100\"\n\t\t\t\t\theight=\"75\"\n\t\t\t\t\tstyle=\"max-width:100%;\"\n\t\t\t\t\/>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div> \n\t\t\t\n\t\t\t\t<div id=\"ngg-image-8\" class=\"ngg-gallery-thumbnail-box \n\t\t\t\t\t\t\t\t\t\t\t\" \n\t\t\t>\n\t\t\t\t\t\t<div class=\"ngg-gallery-thumbnail\">\n\t\t\t<a href=\"https:\/\/china-by-bike.de\/blog\/wp-content\/gallery\/2013-03-18_nepal131\/dsc1161.jpg\"\n\t\t\t\ttitle=\"\"\n\t\t\t\tdata-src=\"https:\/\/china-by-bike.de\/blog\/wp-content\/gallery\/2013-03-18_nepal131\/dsc1161.jpg\"\n\t\t\t\tdata-thumbnail=\"https:\/\/china-by-bike.de\/blog\/wp-content\/gallery\/2013-03-18_nepal131\/thumbs\/thumbs_dsc1161.jpg\"\n\t\t\t\tdata-image-id=\"13643\"\n\t\t\t\tdata-title=\"dsc1161\"\n\t\t\t\tdata-description=\"\"\n\t\t\t\tdata-image-slug=\"dsc1161\"\n\t\t\t\tclass=\"shutterset_31abfd1a5262faf99e179bde2ee4dc14\">\n\t\t\t\t<img\n\t\t\t\t\ttitle=\"dsc1161\"\n\t\t\t\t\talt=\"dsc1161\"\n\t\t\t\t\tsrc=\"https:\/\/china-by-bike.de\/blog\/wp-content\/gallery\/2013-03-18_nepal131\/thumbs\/thumbs_dsc1161.jpg\"\n\t\t\t\t\twidth=\"100\"\n\t\t\t\t\theight=\"75\"\n\t\t\t\t\tstyle=\"max-width:100%;\"\n\t\t\t\t\/>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div> \n\t\t\t\n\t\t\t\t<div id=\"ngg-image-9\" class=\"ngg-gallery-thumbnail-box \n\t\t\t\t\t\t\t\t\t\t\t\" \n\t\t\t>\n\t\t\t\t\t\t<div class=\"ngg-gallery-thumbnail\">\n\t\t\t<a href=\"https:\/\/china-by-bike.de\/blog\/wp-content\/gallery\/2013-03-18_nepal131\/dsc1165.jpg\"\n\t\t\t\ttitle=\"\"\n\t\t\t\tdata-src=\"https:\/\/china-by-bike.de\/blog\/wp-content\/gallery\/2013-03-18_nepal131\/dsc1165.jpg\"\n\t\t\t\tdata-thumbnail=\"https:\/\/china-by-bike.de\/blog\/wp-content\/gallery\/2013-03-18_nepal131\/thumbs\/thumbs_dsc1165.jpg\"\n\t\t\t\tdata-image-id=\"13644\"\n\t\t\t\tdata-title=\"dsc1165\"\n\t\t\t\tdata-description=\"\"\n\t\t\t\tdata-image-slug=\"dsc1165\"\n\t\t\t\tclass=\"shutterset_31abfd1a5262faf99e179bde2ee4dc14\">\n\t\t\t\t<img\n\t\t\t\t\ttitle=\"dsc1165\"\n\t\t\t\t\talt=\"dsc1165\"\n\t\t\t\t\tsrc=\"https:\/\/china-by-bike.de\/blog\/wp-content\/gallery\/2013-03-18_nepal131\/thumbs\/thumbs_dsc1165.jpg\"\n\t\t\t\t\twidth=\"100\"\n\t\t\t\t\theight=\"75\"\n\t\t\t\t\tstyle=\"max-width:100%;\"\n\t\t\t\t\/>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div> \n\t\t\t\n\t\t\t\t<div id=\"ngg-image-10\" class=\"ngg-gallery-thumbnail-box \n\t\t\t\t\t\t\t\t\t\t\t\" \n\t\t\t>\n\t\t\t\t\t\t<div class=\"ngg-gallery-thumbnail\">\n\t\t\t<a href=\"https:\/\/china-by-bike.de\/blog\/wp-content\/gallery\/2013-03-18_nepal131\/dsc1166.jpg\"\n\t\t\t\ttitle=\"\"\n\t\t\t\tdata-src=\"https:\/\/china-by-bike.de\/blog\/wp-content\/gallery\/2013-03-18_nepal131\/dsc1166.jpg\"\n\t\t\t\tdata-thumbnail=\"https:\/\/china-by-bike.de\/blog\/wp-content\/gallery\/2013-03-18_nepal131\/thumbs\/thumbs_dsc1166.jpg\"\n\t\t\t\tdata-image-id=\"13645\"\n\t\t\t\tdata-title=\"dsc1166\"\n\t\t\t\tdata-description=\"\"\n\t\t\t\tdata-image-slug=\"dsc1166\"\n\t\t\t\tclass=\"shutterset_31abfd1a5262faf99e179bde2ee4dc14\">\n\t\t\t\t<img\n\t\t\t\t\ttitle=\"dsc1166\"\n\t\t\t\t\talt=\"dsc1166\"\n\t\t\t\t\tsrc=\"https:\/\/china-by-bike.de\/blog\/wp-content\/gallery\/2013-03-18_nepal131\/thumbs\/thumbs_dsc1166.jpg\"\n\t\t\t\t\twidth=\"100\"\n\t\t\t\t\theight=\"75\"\n\t\t\t\t\tstyle=\"max-width:100%;\"\n\t\t\t\t\/>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div> \n\t\t\t\n\t\t\t\t<div id=\"ngg-image-11\" class=\"ngg-gallery-thumbnail-box \n\t\t\t\t\t\t\t\t\t\t\t\" \n\t\t\t>\n\t\t\t\t\t\t<div class=\"ngg-gallery-thumbnail\">\n\t\t\t<a href=\"https:\/\/china-by-bike.de\/blog\/wp-content\/gallery\/2013-03-18_nepal131\/dsc1170.jpg\"\n\t\t\t\ttitle=\"\"\n\t\t\t\tdata-src=\"https:\/\/china-by-bike.de\/blog\/wp-content\/gallery\/2013-03-18_nepal131\/dsc1170.jpg\"\n\t\t\t\tdata-thumbnail=\"https:\/\/china-by-bike.de\/blog\/wp-content\/gallery\/2013-03-18_nepal131\/thumbs\/thumbs_dsc1170.jpg\"\n\t\t\t\tdata-image-id=\"13646\"\n\t\t\t\tdata-title=\"dsc1170\"\n\t\t\t\tdata-description=\"\"\n\t\t\t\tdata-image-slug=\"dsc1170\"\n\t\t\t\tclass=\"shutterset_31abfd1a5262faf99e179bde2ee4dc14\">\n\t\t\t\t<img\n\t\t\t\t\ttitle=\"dsc1170\"\n\t\t\t\t\talt=\"dsc1170\"\n\t\t\t\t\tsrc=\"https:\/\/china-by-bike.de\/blog\/wp-content\/gallery\/2013-03-18_nepal131\/thumbs\/thumbs_dsc1170.jpg\"\n\t\t\t\t\twidth=\"100\"\n\t\t\t\t\theight=\"75\"\n\t\t\t\t\tstyle=\"max-width:100%;\"\n\t\t\t\t\/>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div> \n\t\t\t\n\t\t\t\t<div id=\"ngg-image-12\" class=\"ngg-gallery-thumbnail-box \n\t\t\t\t\t\t\t\t\t\t\t\" \n\t\t\t>\n\t\t\t\t\t\t<div class=\"ngg-gallery-thumbnail\">\n\t\t\t<a href=\"https:\/\/china-by-bike.de\/blog\/wp-content\/gallery\/2013-03-18_nepal131\/dsc1175.jpg\"\n\t\t\t\ttitle=\"\"\n\t\t\t\tdata-src=\"https:\/\/china-by-bike.de\/blog\/wp-content\/gallery\/2013-03-18_nepal131\/dsc1175.jpg\"\n\t\t\t\tdata-thumbnail=\"https:\/\/china-by-bike.de\/blog\/wp-content\/gallery\/2013-03-18_nepal131\/thumbs\/thumbs_dsc1175.jpg\"\n\t\t\t\tdata-image-id=\"13647\"\n\t\t\t\tdata-title=\"dsc1175\"\n\t\t\t\tdata-description=\"\"\n\t\t\t\tdata-image-slug=\"dsc1175\"\n\t\t\t\tclass=\"shutterset_31abfd1a5262faf99e179bde2ee4dc14\">\n\t\t\t\t<img\n\t\t\t\t\ttitle=\"dsc1175\"\n\t\t\t\t\talt=\"dsc1175\"\n\t\t\t\t\tsrc=\"https:\/\/china-by-bike.de\/blog\/wp-content\/gallery\/2013-03-18_nepal131\/thumbs\/thumbs_dsc1175.jpg\"\n\t\t\t\t\twidth=\"100\"\n\t\t\t\t\theight=\"75\"\n\t\t\t\t\tstyle=\"max-width:100%;\"\n\t\t\t\t\/>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div> \n\t\t\t\n\t\n\t<br style=\"clear: both\" \/>\n\n\t\t<div class=\"slideshowlink\">\n\t\t<a href='https:\/\/china-by-bike.de\/blog\/2013\/03\/the-long-way-down\/nggallery\/slideshow'>[Show as slideshow]<\/a>\n\t\t\n\t<\/div>\n\t\n\t\t<!-- Pagination -->\n\t\t<div class='ngg-clear'><\/div>\t<\/div>\n<br \/>\n[map style=&#8220;width: auto; height:400px; margin:20px 0px 20px 0px; border: 1px solid black;&#8220; gpx=&#8220;https:\/\/china-by-bike.de\/blog\/wp-content\/uploads\/2013\/03\/2013-03-18_Nepal131.gpx&#8220;]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>An den H\u00e4ngen des Himalaya, 14.03. bis 07.04.2013 68 km vom Last Resort nach Dulikhel &#8211; allerlei Abst\u00fcrze und ein Schlussanstieg bei sommerlichen 30 Grad Die V\u00f6gel zwitschern, die Bl\u00e4tter rauschen, nur alle 15 Minuten dringt die Sirene eines auf der anderen Seite des Tales vorbefahrenden Busses zu uns her\u00fcber. Wir sitzen im gr\u00fcnen Garten des Last Resorts und genie\u00dfen die Morgensonne beim Fr\u00fchst\u00fcck. Und von nun an ging`s bergab&#8230; Manfred hat es also gewagt. Nachdem er schon letztes Jahr&#8230;<\/p>\n<p class=\"continue-reading-button\"> <a class=\"continue-reading-link\" href=\"https:\/\/china-by-bike.de\/blog\/2013\/03\/the-long-way-down\/\">Weiter lesen!<i class=\"crycon-right-dir\"><\/i><\/a><\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[50],"tags":[199],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/china-by-bike.de\/blog\/wp-json\/wp\/v2\/posts\/7698"}],"collection":[{"href":"https:\/\/china-by-bike.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/china-by-bike.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/china-by-bike.de\/blog\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/china-by-bike.de\/blog\/wp-json\/wp\/v2\/comments?post=7698"}],"version-history":[{"count":18,"href":"https:\/\/china-by-bike.de\/blog\/wp-json\/wp\/v2\/posts\/7698\/revisions"}],"predecessor-version":[{"id":11914,"href":"https:\/\/china-by-bike.de\/blog\/wp-json\/wp\/v2\/posts\/7698\/revisions\/11914"}],"wp:attachment":[{"href":"https:\/\/china-by-bike.de\/blog\/wp-json\/wp\/v2\/media?parent=7698"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/china-by-bike.de\/blog\/wp-json\/wp\/v2\/categories?post=7698"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/china-by-bike.de\/blog\/wp-json\/wp\/v2\/tags?post=7698"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}